{"id":5544,"count":1,"description":"","link":"https:\/\/www.snowtrex.co.uk\/magazine\/tag\/fai_della_paganella\/","name":"Fai della Paganella","slug":"fai_della_paganella","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fai della Paganella - SnowTrex Ski Magazine<\/title>\n<meta name=\"description\" content=\"Fai della Paganella - SnowTrex Ski Magazine\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fai della Paganella\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.co.uk\/magazine\/tag\/fai_della_paganella\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex Ski Magazine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/tag\\\/fai_della_paganella\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/tag\\\/fai_della_paganella\\\/\",\"name\":\"Fai della Paganella - SnowTrex Ski Magazine\",\"description\":\"Fai della Paganella - SnowTrex Ski Magazine\",\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/\",\"name\":\"SnowTrex Ski Magazine\",\"description\":\"Everything about skiing, snowboarding and winter holidays!\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/#organization\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SnowTrex.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\"],\"description\":\"SnowTrex has been Germany's leading tour operator for skiing holidays since 1999. The company markets its offers in 13 languages and brings over 100,000 guests a year to popular destinations such as Austria, France, Italy, Switzerland and Germany.\",\"email\":\"info-uk@snowtrex.com\",\"telephone\":\"+44 34 539 964 07\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fai della Paganella - SnowTrex Ski Magazine","description":"Fai della Paganella - SnowTrex Ski Magazine","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Fai della Paganella","og_url":"https:\/\/www.snowtrex.co.uk\/magazine\/tag\/fai_della_paganella\/","og_site_name":"SnowTrex Ski Magazine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.snowtrex.co.uk\/magazine\/tag\/fai_della_paganella\/","url":"https:\/\/www.snowtrex.co.uk\/magazine\/tag\/fai_della_paganella\/","name":"Fai della Paganella - SnowTrex Ski Magazine","description":"Fai della Paganella - SnowTrex Ski Magazine","inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.co.uk\/magazine\/#website","url":"https:\/\/www.snowtrex.co.uk\/magazine\/","name":"SnowTrex Ski Magazine","description":"Everything about skiing, snowboarding and winter holidays!","publisher":{"@id":"https:\/\/www.snowtrex.co.uk\/magazine\/#organization"},"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.co.uk\/magazine\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.co.uk\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.snowtrex.co.uk\/magazine\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.co.uk\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SnowTrex.de\/","https:\/\/www.instagram.com\/snowtrex_ski\/"],"description":"SnowTrex has been Germany's leading tour operator for skiing holidays since 1999. The company markets its offers in 13 languages and brings over 100,000 guests a year to popular destinations such as Austria, France, Italy, Switzerland and Germany.","email":"info-uk@snowtrex.com","telephone":"+44 34 539 964 07","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.snowtrex.co.uk\/magazine\/wp-json\/wp\/v2\/tags\/5544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.co.uk\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.snowtrex.co.uk\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.snowtrex.co.uk\/magazine\/wp-json\/wp\/v2\/posts?tags=5544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}